{"id":4123,"date":"2025-10-07T01:33:52","date_gmt":"2025-10-06T17:33:52","guid":{"rendered":"https:\/\/www.ryagroparts.com\/?post_type=product&#038;p=4123"},"modified":"2025-10-07T01:41:16","modified_gmt":"2025-10-06T17:41:16","slug":"segmento-de-cono-copy","status":"publish","type":"product","link":"https:\/\/www.ryagroparts.com\/es\/producto\/segmento-de-cono-copy\/","title":{"rendered":"Sinf\u00edn con disco de acoplamiento"},"content":{"rendered":"<p data-start=\"34\" data-end=\"237\">La barrena Orbis con disco de <strong data-start=\"38\" data-end=\"71\">acoplamiento<\/strong> es un producto de posventa de alta calidad dise\u00f1ado para Orbis. Fabricado con materiales duraderos y confiables, garantiza un excelente rendimiento y una larga vida \u00fatil. <\/p>\n<p data-start=\"239\" data-end=\"342\">Este producto es compatible con las m\u00e1quinas de placa de disco de acoplamiento Orbis Auger With Coupling y hace referencias cruzadas a los siguientes c\u00f3digos OEM:<\/p>\n<ul data-start=\"344\" data-end=\"388\">\n<li data-start=\"344\" data-end=\"358\">4997022<\/li>\n<li data-start=\"344\" data-end=\"358\">4970410<\/li>\n<\/ul>\n<p data-start=\"390\" data-end=\"532\">\u26a0\ufe0f <strong data-start=\"393\" data-end=\"401\">Nota<\/strong>: [Orbis] \u00ae es una marca registrada. Los n\u00fameros de pieza son solo para referencia y compatibilidad. Esta no es una pieza OEM original.  <\/p>\n<p><script src=\"chrome-extension:\/\/fpelahbljekknahkcaegamhcndkfpfnc\/iFrame.js\" type=\"text\/javascript\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p data-start=\"34\" data-end=\"237\">La barrena Orbis con disco de <strong data-start=\"38\" data-end=\"71\">acoplamiento<\/strong> es un producto de posventa de alta calidad dise\u00f1ado para Orbis. Fabricado con materiales duraderos y confiables, garantiza un excelente rendimiento y una larga vida \u00fatil. <\/p>\n<p data-start=\"239\" data-end=\"342\">Este producto es compatible con las m\u00e1quinas de placa de disco de acoplamiento Orbis Auger With Coupling y hace referencias cruzadas a los siguientes c\u00f3digos OEM:<\/p>\n<ul data-start=\"344\" data-end=\"388\">\n<li data-start=\"344\" data-end=\"358\">4997022<\/li>\n<li data-start=\"344\" data-end=\"358\">4970410<\/li>\n<\/ul>\n<p data-start=\"390\" data-end=\"532\">\u26a0\ufe0f <strong data-start=\"393\" data-end=\"401\">Nota<\/strong>: [Orbis] \u00ae es una marca registrada. Los n\u00fameros de pieza son solo para referencia y compatibilidad. Esta no es una pieza OEM original.  <\/p>\n<p><script src=\"chrome-extension:\/\/fpelahbljekknahkcaegamhcndkfpfnc\/iFrame.js\" type=\"text\/javascript\"><\/script><\/p>\n","protected":false},"featured_media":4129,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[95],"product_tag":[],"class_list":{"0":"post-4123","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-orbis-encabezado","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.ryagroparts.com\/es\/wp-json\/wp\/v2\/product\/4123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ryagroparts.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ryagroparts.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ryagroparts.com\/es\/wp-json\/wp\/v2\/comments?post=4123"}],"version-history":[{"count":2,"href":"https:\/\/www.ryagroparts.com\/es\/wp-json\/wp\/v2\/product\/4123\/revisions"}],"predecessor-version":[{"id":4134,"href":"https:\/\/www.ryagroparts.com\/es\/wp-json\/wp\/v2\/product\/4123\/revisions\/4134"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ryagroparts.com\/es\/wp-json\/wp\/v2\/media\/4129"}],"wp:attachment":[{"href":"https:\/\/www.ryagroparts.com\/es\/wp-json\/wp\/v2\/media?parent=4123"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.ryagroparts.com\/es\/wp-json\/wp\/v2\/product_brand?post=4123"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ryagroparts.com\/es\/wp-json\/wp\/v2\/product_cat?post=4123"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ryagroparts.com\/es\/wp-json\/wp\/v2\/product_tag?post=4123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}