{"id":5479,"date":"2025-10-08T01:25:00","date_gmt":"2025-10-07T17:25:00","guid":{"rendered":"https:\/\/www.ryagroparts.com\/?post_type=product&#038;p=5479"},"modified":"2025-10-08T01:26:56","modified_gmt":"2025-10-07T17:26:56","slug":"borde-dentado-copy-3","status":"publish","type":"product","link":"https:\/\/www.ryagroparts.com\/es\/producto\/borde-dentado-copy-3\/","title":{"rendered":"Eje helicoidal"},"content":{"rendered":"<p data-start=\"34\" data-end=\"237\">La <strong data-start=\"38\" data-end=\"71\">pieza de repuesto<\/strong> del eje helicoidal Claas es un producto de posventa de alta calidad dise\u00f1ado para Claas. Fabricado con materiales duraderos y confiables, garantiza un excelente rendimiento y una larga vida \u00fatil. <\/p>\n<p data-start=\"239\" data-end=\"342\">Este producto es compatible con las m\u00e1quinas de placa de eje helicoidal Claas y hace referencias cruzadas a los siguientes c\u00f3digos OEM:<\/p>\n<ul data-start=\"344\" data-end=\"388\">\n<li data-start=\"344\" data-end=\"358\">  00901260<\/li>\n<\/ul>\n<p data-start=\"390\" data-end=\"532\">\u26a0\ufe0f <strong data-start=\"393\" data-end=\"401\">Nota<\/strong>: [Claas] \u00ae es una marca registrada. Los n\u00fameros de pieza son solo para referencia y compatibilidad. Esta no es una pieza OEM original.  <\/p>\n<p>&nbsp;<\/p>\n<p><script src=\"chrome-extension:\/\/fpelahbljekknahkcaegamhcndkfpfnc\/iFrame.js\" type=\"text\/javascript\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p data-start=\"34\" data-end=\"237\">La <strong data-start=\"38\" data-end=\"71\">pieza de repuesto<\/strong> del eje helicoidal Claas es un producto de posventa de alta calidad dise\u00f1ado para Claas. Fabricado con materiales duraderos y confiables, garantiza un excelente rendimiento y una larga vida \u00fatil. <\/p>\n<p data-start=\"239\" data-end=\"342\">Este producto es compatible con las m\u00e1quinas de placa de eje helicoidal Claas y hace referencias cruzadas a los siguientes c\u00f3digos OEM:<\/p>\n<ul data-start=\"344\" data-end=\"388\">\n<li data-start=\"344\" data-end=\"358\">  00901260<\/li>\n<\/ul>\n<p data-start=\"390\" data-end=\"532\">\u26a0\ufe0f <strong data-start=\"393\" data-end=\"401\">Nota<\/strong>: [Claas] \u00ae es una marca registrada. Los n\u00fameros de pieza son solo para referencia y compatibilidad. Esta no es una pieza OEM original.  <\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":5485,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[81],"product_tag":[],"class_list":{"0":"post-5479","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-claas-es","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.ryagroparts.com\/es\/wp-json\/wp\/v2\/product\/5479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ryagroparts.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ryagroparts.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ryagroparts.com\/es\/wp-json\/wp\/v2\/comments?post=5479"}],"version-history":[{"count":2,"href":"https:\/\/www.ryagroparts.com\/es\/wp-json\/wp\/v2\/product\/5479\/revisions"}],"predecessor-version":[{"id":5490,"href":"https:\/\/www.ryagroparts.com\/es\/wp-json\/wp\/v2\/product\/5479\/revisions\/5490"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ryagroparts.com\/es\/wp-json\/wp\/v2\/media\/5485"}],"wp:attachment":[{"href":"https:\/\/www.ryagroparts.com\/es\/wp-json\/wp\/v2\/media?parent=5479"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.ryagroparts.com\/es\/wp-json\/wp\/v2\/product_brand?post=5479"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ryagroparts.com\/es\/wp-json\/wp\/v2\/product_cat?post=5479"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ryagroparts.com\/es\/wp-json\/wp\/v2\/product_tag?post=5479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}