{"id":5646,"date":"2025-10-08T02:35:18","date_gmt":"2025-10-07T18:35:18","guid":{"rendered":"https:\/\/www.ryagroparts.com\/?post_type=product&#038;p=5646"},"modified":"2025-10-08T02:37:04","modified_gmt":"2025-10-07T18:37:04","slug":"revestimiento-de-boquilla-de-extension-media-copy","status":"publish","type":"product","link":"https:\/\/www.ryagroparts.com\/es\/producto\/revestimiento-de-boquilla-de-extension-media-copy\/","title":{"rendered":"Placa trasera del rodillo de alimentaci\u00f3n"},"content":{"rendered":"<p data-start=\"34\" data-end=\"237\">La <strong data-start=\"38\" data-end=\"71\">pieza de repuesto<\/strong> de la placa trasera del rodillo de alimentaci\u00f3n Claas es un producto de posventa de alta calidad dise\u00f1ado para Claas. Fabricado con materiales duraderos y confiables, garantiza un excelente rendimiento y una larga vida \u00fatil. <\/p>\n<p data-start=\"239\" data-end=\"342\">Este producto es compatible con las m\u00e1quinas Claas Feed Roller Rear Plate Plate Plate y hace referencias cruzadas a los siguientes c\u00f3digos OEM:<\/p>\n<ul data-start=\"344\" data-end=\"388\">\n<li data-start=\"344\" data-end=\"358\">\n<p data-start=\"346\" data-end=\"358\">9842905<\/p>\n<\/li>\n<li data-start=\"344\" data-end=\"358\">\n<p data-start=\"346\" data-end=\"358\">9842901<\/p>\n<\/li>\n<li data-start=\"344\" data-end=\"358\">\n<p data-start=\"346\" data-end=\"358\">4956811<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"390\" data-end=\"532\">\u26a0\ufe0f <strong data-start=\"393\" data-end=\"401\">Nota<\/strong>: [Claas] \u00ae es una marca registrada. Los n\u00fameros de pieza son solo para referencia y compatibilidad. Esta no es una pieza OEM original.  <\/p>\n<p><script src=\"chrome-extension:\/\/fpelahbljekknahkcaegamhcndkfpfnc\/iFrame.js\" type=\"text\/javascript\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p data-start=\"34\" data-end=\"237\">La <strong data-start=\"38\" data-end=\"71\">pieza de repuesto<\/strong> de la placa trasera del rodillo de alimentaci\u00f3n Claas es un producto de posventa de alta calidad dise\u00f1ado para Claas. Fabricado con materiales duraderos y confiables, garantiza un excelente rendimiento y una larga vida \u00fatil. <\/p>\n<p data-start=\"239\" data-end=\"342\">Este producto es compatible con las m\u00e1quinas Claas Feed Roller Rear Plate Plate Plate y hace referencias cruzadas a los siguientes c\u00f3digos OEM:<\/p>\n<ul data-start=\"344\" data-end=\"388\">\n<li data-start=\"344\" data-end=\"358\">\n<p data-start=\"346\" data-end=\"358\">9842905<\/p>\n<\/li>\n<li data-start=\"344\" data-end=\"358\">\n<p data-start=\"346\" data-end=\"358\">9842901<\/p>\n<\/li>\n<li data-start=\"344\" data-end=\"358\">\n<p data-start=\"346\" data-end=\"358\">4956811<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"390\" data-end=\"532\">\u26a0\ufe0f <strong data-start=\"393\" data-end=\"401\">Nota<\/strong>: [Claas] \u00ae es una marca registrada. Los n\u00fameros de pieza son solo para referencia y compatibilidad. Esta no es una pieza OEM original.  <\/p>\n<p><script src=\"chrome-extension:\/\/fpelahbljekknahkcaegamhcndkfpfnc\/iFrame.js\" type=\"text\/javascript\"><\/script><\/p>\n","protected":false},"featured_media":5652,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[81],"product_tag":[],"class_list":{"0":"post-5646","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-claas-es","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.ryagroparts.com\/es\/wp-json\/wp\/v2\/product\/5646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ryagroparts.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ryagroparts.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ryagroparts.com\/es\/wp-json\/wp\/v2\/comments?post=5646"}],"version-history":[{"count":2,"href":"https:\/\/www.ryagroparts.com\/es\/wp-json\/wp\/v2\/product\/5646\/revisions"}],"predecessor-version":[{"id":5657,"href":"https:\/\/www.ryagroparts.com\/es\/wp-json\/wp\/v2\/product\/5646\/revisions\/5657"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ryagroparts.com\/es\/wp-json\/wp\/v2\/media\/5652"}],"wp:attachment":[{"href":"https:\/\/www.ryagroparts.com\/es\/wp-json\/wp\/v2\/media?parent=5646"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.ryagroparts.com\/es\/wp-json\/wp\/v2\/product_brand?post=5646"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ryagroparts.com\/es\/wp-json\/wp\/v2\/product_cat?post=5646"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ryagroparts.com\/es\/wp-json\/wp\/v2\/product_tag?post=5646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}