{"id":3717,"date":"2025-09-03T22:52:27","date_gmt":"2025-09-03T14:52:27","guid":{"rendered":"https:\/\/www.ryagroparts.com\/?post_type=product&#038;p=3717"},"modified":"2025-09-03T22:57:01","modified_gmt":"2025-09-03T14:57:01","slug":"lame-de-coupe-kemper-copy","status":"publish","type":"product","link":"https:\/\/www.ryagroparts.com\/fr\/produit\/lame-de-coupe-kemper-copy\/","title":{"rendered":"Pierre \u00e0 aiguiser"},"content":{"rendered":"<p data-start=\"34\" data-end=\"237\">La <strong data-start=\"38\" data-end=\"71\">pi\u00e8ce de rechange<\/strong> pour pierre \u00e0 aiguiser Class est un produit de rechange de haute qualit\u00e9 con\u00e7u pour la classe. Fabriqu\u00e9 \u00e0 partir de mat\u00e9riaux durables et fiables, il garantit d\u2019excellentes performances et une longue dur\u00e9e de vie. <\/p>\n<p data-start=\"239\" data-end=\"342\">Ce produit est compatible avec les machines \u00e0 plaques de pierre \u00e0 aiguiser de classe et fait r\u00e9f\u00e9rence aux codes OEM suivants :<\/p>\n<ul data-start=\"344\" data-end=\"388\">\n<li data-start=\"344\" data-end=\"358\">\n<p data-start=\"346\" data-end=\"358\">13124424, 13124423, 13124422, 13124421, 13124420, 13904550<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"390\" data-end=\"532\">\u26a0\ufe0f <strong data-start=\"393\" data-end=\"401\">Remarque<\/strong> : [Classe] \u00ae est une marque d\u00e9pos\u00e9e. Les num\u00e9ros de pi\u00e8ce sont fournis \u00e0 titre indicatif et de compatibilit\u00e9 uniquement. Il ne s\u2019agit pas d\u2019une pi\u00e8ce d\u2019origine OEM.  <\/p>\n<p><script src=\"chrome-extension:\/\/fpelahbljekknahkcaegamhcndkfpfnc\/iFrame.js\" type=\"text\/javascript\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p data-start=\"34\" data-end=\"237\">La <strong data-start=\"38\" data-end=\"71\">pi\u00e8ce de rechange<\/strong> pour pierre \u00e0 aiguiser Class est un produit de rechange de haute qualit\u00e9 con\u00e7u pour la classe. Fabriqu\u00e9 \u00e0 partir de mat\u00e9riaux durables et fiables, il garantit d\u2019excellentes performances et une longue dur\u00e9e de vie. <\/p>\n<p data-start=\"239\" data-end=\"342\">Ce produit est compatible avec les machines \u00e0 plaques de pierre \u00e0 aiguiser de classe et fait r\u00e9f\u00e9rence aux codes OEM suivants :<\/p>\n<ul data-start=\"344\" data-end=\"388\">\n<li data-start=\"344\" data-end=\"358\">\n<p data-start=\"346\" data-end=\"358\">13124424, 13124423, 13124422, 13124421, 13124420, 13904550<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"390\" data-end=\"532\">\u26a0\ufe0f <strong data-start=\"393\" data-end=\"401\">Remarque<\/strong> : [Classe] \u00ae est une marque d\u00e9pos\u00e9e. Les num\u00e9ros de pi\u00e8ce sont fournis \u00e0 titre indicatif et de compatibilit\u00e9 uniquement. Il ne s\u2019agit pas d\u2019une pi\u00e8ce d\u2019origine OEM.  <\/p>\n<p data-start=\"34\" data-end=\"237\"><script src=\"chrome-extension:\/\/fpelahbljekknahkcaegamhcndkfpfnc\/iFrame.js\" type=\"text\/javascript\"><\/script><\/p>\n<p><script src=\"chrome-extension:\/\/fpelahbljekknahkcaegamhcndkfpfnc\/iFrame.js\" type=\"text\/javascript\"><\/script><\/p>\n","protected":false},"featured_media":3720,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[83],"product_tag":[],"class_list":{"0":"post-3717","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-claas-fr","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.ryagroparts.com\/fr\/wp-json\/wp\/v2\/product\/3717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ryagroparts.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ryagroparts.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ryagroparts.com\/fr\/wp-json\/wp\/v2\/comments?post=3717"}],"version-history":[{"count":2,"href":"https:\/\/www.ryagroparts.com\/fr\/wp-json\/wp\/v2\/product\/3717\/revisions"}],"predecessor-version":[{"id":3729,"href":"https:\/\/www.ryagroparts.com\/fr\/wp-json\/wp\/v2\/product\/3717\/revisions\/3729"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ryagroparts.com\/fr\/wp-json\/wp\/v2\/media\/3720"}],"wp:attachment":[{"href":"https:\/\/www.ryagroparts.com\/fr\/wp-json\/wp\/v2\/media?parent=3717"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.ryagroparts.com\/fr\/wp-json\/wp\/v2\/product_brand?post=3717"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ryagroparts.com\/fr\/wp-json\/wp\/v2\/product_cat?post=3717"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ryagroparts.com\/fr\/wp-json\/wp\/v2\/product_tag?post=3717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}